{"id":191,"date":"2025-10-17T17:26:25","date_gmt":"2025-10-17T17:26:25","guid":{"rendered":"https:\/\/med.virginia.edu\/spatial-biology-core\/?page_id=191"},"modified":"2026-02-16T20:14:28","modified_gmt":"2026-02-16T20:14:28","slug":"rawtunda","status":"publish","type":"page","link":"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/","title":{"rendered":"RAWtunda"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1673,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"tags":[],"class_list":["post-191","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RAWtunda - Spatial Biology Core<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RAWtunda - Spatial Biology Core\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/\" \/>\n<meta property=\"og:site_name\" content=\"Spatial Biology Core\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T20:14:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/rawtunda\\\/\",\"url\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/rawtunda\\\/\",\"name\":\"RAWtunda - Spatial Biology Core\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/#website\"},\"datePublished\":\"2025-10-17T17:26:25+00:00\",\"dateModified\":\"2026-02-16T20:14:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/rawtunda\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/rawtunda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/rawtunda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RAWtunda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/#website\",\"url\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/\",\"name\":\"Spatial Biology Core\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/med.virginia.edu\\\/spatial-biology-core\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RAWtunda - Spatial Biology Core","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/","og_locale":"en_US","og_type":"article","og_title":"RAWtunda - Spatial Biology Core","og_url":"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/","og_site_name":"Spatial Biology Core","article_modified_time":"2026-02-16T20:14:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/","url":"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/","name":"RAWtunda - Spatial Biology Core","isPartOf":{"@id":"https:\/\/med.virginia.edu\/spatial-biology-core\/#website"},"datePublished":"2025-10-17T17:26:25+00:00","dateModified":"2026-02-16T20:14:28+00:00","breadcrumb":{"@id":"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/med.virginia.edu\/spatial-biology-core\/rawtunda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.virginia.edu\/spatial-biology-core\/"},{"@type":"ListItem","position":2,"name":"RAWtunda"}]},{"@type":"WebSite","@id":"https:\/\/med.virginia.edu\/spatial-biology-core\/#website","url":"https:\/\/med.virginia.edu\/spatial-biology-core\/","name":"Spatial Biology Core","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.virginia.edu\/spatial-biology-core\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/pages\/191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/users\/1673"}],"replies":[{"embeddable":true,"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/comments?post=191"}],"version-history":[{"count":6,"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/pages\/191\/revisions"}],"predecessor-version":[{"id":271,"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/pages\/191\/revisions\/271"}],"wp:attachment":[{"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/media?parent=191"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.virginia.edu\/spatial-biology-core\/wp-json\/wp\/v2\/tags?post=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}